{"id":567,"date":"2019-01-30T07:55:14","date_gmt":"2019-01-30T07:55:14","guid":{"rendered":"http:\/\/sobreruedas.hdnweb.com\/?p=567"},"modified":"2019-10-31T15:48:54","modified_gmt":"2019-10-31T15:48:54","slug":"un-bravo-pueblo-cubierto-de-gloria","status":"publish","type":"post","link":"https:\/\/sobreruedas.us\/en\/un-bravo-pueblo-cubierto-de-gloria\/","title":{"rendered":"Un bravo pueblo cubierto de gloria"},"content":{"rendered":"<p>Las \u00faltimas semanas nos han permitido ser testigos de unos acontecimientos que podr\u00edan traer consecuencias muy significativas para el futuro cercano, inicialmente de Venezuela y posteriormente del resto de la regi\u00f3n latinoamericana, particularmente de los pa\u00edses que resultaron v\u00edctimas de la peste del socialismo del siglo 21. Lo que viene sucediendo en Venezuela es de una importancia superlativa. No es, evidentemente, la primera vez que la gente sale masivamente a protestar a las calles contra el r\u00e9gimen fracasado, corrupto, narcoterrorista y represivo de Nicol\u00e1s Maduro y su pandilla de matones. Han sido muchas las oportunidades en que los venezolanos han cumplido con su deber c\u00edvico y han llenado las calles y los espacios p\u00fablicos para manifestar su inconformismo. Y es cierto, nada tangible han conseguido cambiar, pero esta vez es inmensamente distinto.<br \/>\nLo que cambia todo es el hecho irrefutable de que, en esta ocasi\u00f3n, de las protestas ha surgido una cabeza visible que logr\u00f3 disparar el reconocimiento inmediato de una cantidad notable de muy respetables gobiernos en todo el mundo, comenzando con el de los Estados Unidos que, dicho sea de paso, es la naci\u00f3n que cuenta con el m\u00fasculo suficiente, tanto econ\u00f3mico como militar, para presionar a lo que queda de la dictadura de Maduro a que tome la decisi\u00f3n de hacerse a un lado y permitir el regreso de la justicia y la democracia, la paz y la libertad, el abastecimiento y la prosperidad,<br \/>\nFalta lo m\u00e1s importante, es cierto, que Maduro caiga, por las buenas o no, y obviamente lo ideal es que esto suceda sin que sea necesario derramar una sola gota de sangre. Conseguir eso es pr\u00e1cticamente imposible, o por lo menos muy dif\u00edcil, sin que las fuerzas armadas tomen finalmente la decisi\u00f3n de cambiar de bando, es decir, darle la espalda a la dictadura corrupta y abrazar la soberana voluntad del pueblo del que hacen parte. Para eso va a ser necesario un enorme poder de convicci\u00f3n, recursos para atraerlos y venderles la idea de que est\u00e1n en una singular encrucijada entre pasar a la historia como cobardes o como h\u00e9roes, enfrentar la justicia en el pr\u00f3ximo gobierno democr\u00e1tico, o acogerse a un proceso de amnist\u00eda y poder vivir en paz en la nueva Venezuela que est\u00e1 por llegar.<br \/>\nPero no es solo en las fuerzas armadas que hay que arreglar ciertas cosas. La oposici\u00f3n tiene tambi\u00e9n que cumplir con lo suyo, y lo m\u00e1s importante es conseguir que cesen las divisiones y los enfrentamientos. Hoy, tras los acontecimientos de las \u00faltimas semanas, la causa es una sola: fortalecer al Presidente Encargado Juan Guaid\u00f3. En t\u00e9rminos pr\u00e1cticos, es fundamental entender que como est\u00e1n las cosas, no estar con Guaid\u00f3 significa estar con Maduro. No se trata de ignorar que hay partidos, tendencias, aspiraciones y, naturalmente, candidatos, Pero ya llegar\u00e1 el momento para eso, cuando Maduro caiga y Guaid\u00f3 asuma y, como lo ha prometido, llame a corto plazo a unas elecciones libres, multipartidistas y con observaci\u00f3n internacional. Y entonces, mientras m\u00e1s opciones mejor. Pero por ahora, la opci\u00f3n es \u00fanica: fuera Maduro!!! <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las \u00faltimas semanas nos han permitido ser testigos de unos acontecimientos que podr\u00edan traer consecuencias muy significativas para el futuro cercano, inicialmente de Venezuela y posteriormente del resto de la regi\u00f3n latinoamericana, particularmente de los pa\u00edses que resultaron v\u00edctimas de la peste del socialismo del siglo 21. Lo que viene sucediendo en Venezuela es de [&hellip;]<\/p>\n","protected":false},"author":50,"featured_media":568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un bravo pueblo cubierto de gloria - Sobre Ruedas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sobreruedas.us\/un-bravo-pueblo-cubierto-de-gloria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un bravo pueblo cubierto de gloria - Sobre Ruedas\" \/>\n<meta property=\"og:description\" content=\"Las \u00faltimas semanas nos han permitido ser testigos de unos acontecimientos que podr\u00edan traer consecuencias muy significativas para el futuro cercano, inicialmente de Venezuela y posteriormente del resto de la regi\u00f3n latinoamericana, particularmente de los pa\u00edses que resultaron v\u00edctimas de la peste del socialismo del siglo 21. Lo que viene sucediendo en Venezuela es de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sobreruedas.us\/un-bravo-pueblo-cubierto-de-gloria\/\" \/>\n<meta property=\"og:site_name\" content=\"Sobre Ruedas\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-30T07:55:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-31T15:48:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sobreruedas.us\/wp-content\/uploads\/sites\/50\/2019\/10\/Venezuela-Flag.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"686\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sobreruedas.us\\\/un-bravo-pueblo-cubierto-de-gloria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sobreruedas.us\\\/un-bravo-pueblo-cubierto-de-gloria\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un bravo pueblo cubierto de gloria\",\"datePublished\":\"2019-01-30T07:55:14+00:00\",\"dateModified\":\"2019-10-31T15:48:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sobreruedas.us\\\/un-bravo-pueblo-cubierto-de-gloria\\\/\"},\"wordCount\":546,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sobreruedas.us\\\/un-bravo-pueblo-cubierto-de-gloria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sobreruedas.us\\\/wp-content\\\/uploads\\\/sites\\\/50\\\/2019\\\/10\\\/Venezuela-Flag.jpg\",\"articleSection\":[\"Opini\u00f3n\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sobreruedas.us\\\/un-bravo-pueblo-cubierto-de-gloria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sobreruedas.us\\\/un-bravo-pueblo-cubierto-de-gloria\\\/\",\"url\":\"https:\\\/\\\/sobreruedas.us\\\/un-bravo-pueblo-cubierto-de-gloria\\\/\",\"name\":\"Un bravo pueblo cubierto de gloria - Sobre Ruedas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sobreruedas.us\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sobreruedas.us\\\/un-bravo-pueblo-cubierto-de-gloria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sobreruedas.us\\\/un-bravo-pueblo-cubierto-de-gloria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sobreruedas.us\\\/wp-content\\\/uploads\\\/sites\\\/50\\\/2019\\\/10\\\/Venezuela-Flag.jpg\",\"datePublished\":\"2019-01-30T07:55:14+00:00\",\"dateModified\":\"2019-10-31T15:48:54+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sobreruedas.us\\\/un-bravo-pueblo-cubierto-de-gloria\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sobreruedas.us\\\/un-bravo-pueblo-cubierto-de-gloria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sobreruedas.us\\\/un-bravo-pueblo-cubierto-de-gloria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sobreruedas.us\\\/wp-content\\\/uploads\\\/sites\\\/50\\\/2019\\\/10\\\/Venezuela-Flag.jpg\",\"contentUrl\":\"https:\\\/\\\/sobreruedas.us\\\/wp-content\\\/uploads\\\/sites\\\/50\\\/2019\\\/10\\\/Venezuela-Flag.jpg\",\"width\":1000,\"height\":686},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sobreruedas.us\\\/un-bravo-pueblo-cubierto-de-gloria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sobreruedas.us\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un bravo pueblo cubierto de gloria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sobreruedas.us\\\/#website\",\"url\":\"https:\\\/\\\/sobreruedas.us\\\/\",\"name\":\"Sobre Ruedas\",\"description\":\"Miembro de HDN\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sobreruedas.us\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/sobreruedas.us\\\/en\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un bravo pueblo cubierto de gloria - Sobre Ruedas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sobreruedas.us\/un-bravo-pueblo-cubierto-de-gloria\/","og_locale":"en_US","og_type":"article","og_title":"Un bravo pueblo cubierto de gloria - Sobre Ruedas","og_description":"Las \u00faltimas semanas nos han permitido ser testigos de unos acontecimientos que podr\u00edan traer consecuencias muy significativas para el futuro cercano, inicialmente de Venezuela y posteriormente del resto de la regi\u00f3n latinoamericana, particularmente de los pa\u00edses que resultaron v\u00edctimas de la peste del socialismo del siglo 21. Lo que viene sucediendo en Venezuela es de [&hellip;]","og_url":"https:\/\/sobreruedas.us\/un-bravo-pueblo-cubierto-de-gloria\/","og_site_name":"Sobre Ruedas","article_published_time":"2019-01-30T07:55:14+00:00","article_modified_time":"2019-10-31T15:48:54+00:00","og_image":[{"width":1000,"height":686,"url":"https:\/\/sobreruedas.us\/wp-content\/uploads\/sites\/50\/2019\/10\/Venezuela-Flag.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sobreruedas.us\/un-bravo-pueblo-cubierto-de-gloria\/#article","isPartOf":{"@id":"https:\/\/sobreruedas.us\/un-bravo-pueblo-cubierto-de-gloria\/"},"author":{"name":"","@id":""},"headline":"Un bravo pueblo cubierto de gloria","datePublished":"2019-01-30T07:55:14+00:00","dateModified":"2019-10-31T15:48:54+00:00","mainEntityOfPage":{"@id":"https:\/\/sobreruedas.us\/un-bravo-pueblo-cubierto-de-gloria\/"},"wordCount":546,"commentCount":0,"image":{"@id":"https:\/\/sobreruedas.us\/un-bravo-pueblo-cubierto-de-gloria\/#primaryimage"},"thumbnailUrl":"https:\/\/sobreruedas.us\/wp-content\/uploads\/sites\/50\/2019\/10\/Venezuela-Flag.jpg","articleSection":["Opini\u00f3n"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sobreruedas.us\/un-bravo-pueblo-cubierto-de-gloria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sobreruedas.us\/un-bravo-pueblo-cubierto-de-gloria\/","url":"https:\/\/sobreruedas.us\/un-bravo-pueblo-cubierto-de-gloria\/","name":"Un bravo pueblo cubierto de gloria - Sobre Ruedas","isPartOf":{"@id":"https:\/\/sobreruedas.us\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sobreruedas.us\/un-bravo-pueblo-cubierto-de-gloria\/#primaryimage"},"image":{"@id":"https:\/\/sobreruedas.us\/un-bravo-pueblo-cubierto-de-gloria\/#primaryimage"},"thumbnailUrl":"https:\/\/sobreruedas.us\/wp-content\/uploads\/sites\/50\/2019\/10\/Venezuela-Flag.jpg","datePublished":"2019-01-30T07:55:14+00:00","dateModified":"2019-10-31T15:48:54+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/sobreruedas.us\/un-bravo-pueblo-cubierto-de-gloria\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sobreruedas.us\/un-bravo-pueblo-cubierto-de-gloria\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sobreruedas.us\/un-bravo-pueblo-cubierto-de-gloria\/#primaryimage","url":"https:\/\/sobreruedas.us\/wp-content\/uploads\/sites\/50\/2019\/10\/Venezuela-Flag.jpg","contentUrl":"https:\/\/sobreruedas.us\/wp-content\/uploads\/sites\/50\/2019\/10\/Venezuela-Flag.jpg","width":1000,"height":686},{"@type":"BreadcrumbList","@id":"https:\/\/sobreruedas.us\/un-bravo-pueblo-cubierto-de-gloria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sobreruedas.us\/"},{"@type":"ListItem","position":2,"name":"Un bravo pueblo cubierto de gloria"}]},{"@type":"WebSite","@id":"https:\/\/sobreruedas.us\/#website","url":"https:\/\/sobreruedas.us\/","name":"Sobre Ruedas","description":"Miembro de HDN","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sobreruedas.us\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"","url":"https:\/\/sobreruedas.us\/en\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/sobreruedas.us\/en\/wp-json\/wp\/v2\/posts\/567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sobreruedas.us\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sobreruedas.us\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sobreruedas.us\/en\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/sobreruedas.us\/en\/wp-json\/wp\/v2\/comments?post=567"}],"version-history":[{"count":2,"href":"https:\/\/sobreruedas.us\/en\/wp-json\/wp\/v2\/posts\/567\/revisions"}],"predecessor-version":[{"id":630,"href":"https:\/\/sobreruedas.us\/en\/wp-json\/wp\/v2\/posts\/567\/revisions\/630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sobreruedas.us\/en\/wp-json\/wp\/v2\/media\/568"}],"wp:attachment":[{"href":"https:\/\/sobreruedas.us\/en\/wp-json\/wp\/v2\/media?parent=567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sobreruedas.us\/en\/wp-json\/wp\/v2\/categories?post=567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sobreruedas.us\/en\/wp-json\/wp\/v2\/tags?post=567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}